{"id":843,"date":"2023-04-13T12:41:44","date_gmt":"2023-04-13T10:41:44","guid":{"rendered":"https:\/\/www.avenida12.com\/contatti\/"},"modified":"2023-05-15T12:22:53","modified_gmt":"2023-05-15T10:22:53","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.avenida12.com\/en\/contact-us\/","title":{"rendered":"Contact us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"843\" class=\"elementor elementor-843 elementor-230\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38c0380 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38c0380\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;split&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 20\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,0v3c0,0,393.8,0,483.4,0c9.2,0,16.6,7.4,16.6,16.6c0-9.1,7.4-16.6,16.6-16.6C606.2,3,1000,3,1000,3V0H0z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e13b9b8\" data-id=\"e13b9b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a066b23 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"4a066b23\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">Contact us<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50893b79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50893b79\" data-element_type=\"section\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;arrow&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a65c437\" data-id=\"3a65c437\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bdab81 elementor-widget elementor-widget-spacer\" data-id=\"9bdab81\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8519044 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8519044\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a776b9c\" data-id=\"a776b9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0cee22 elementor-widget elementor-widget-text-editor\" data-id=\"d0cee22\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: 'DM Serif Text', sans-serif; font-size: 48px;\">Contact us to book your rented room.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bff757 elementor-widget elementor-widget-text-editor\" data-id=\"8bff757\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>And if you wish, request your self check-in. For a relaxing, easy-going and unforgettable stay in Alghero, choose Avenida12!<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68281c8\" data-id=\"68281c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4ef695 elementor-widget elementor-widget-spacer\" data-id=\"a4ef695\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9781a7 elementor-widget elementor-widget-ha-cf7 happy-addon ha-cf7\" data-id=\"f9781a7\" data-element_type=\"widget\" data-widget_type=\"ha-cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1006-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"1006\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/843#wpcf7-f1006-o1\" method=\"post\" class=\"wpcf7-form init ha-cf7-form wpcf7-acceptance-as-validation\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1006\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1006-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Your Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your email<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Your message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p id=\"privacy\"><span class=\"wpcf7-form-control-wrap\" data-name=\"accept-this-3\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"accept-this-3\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ai sensi e per gli effetti degli articoli artt. 7,13 e 15 del Regolamento UE 2016\/679 dichiaro di aver preso visione dell\u2019 <a href=\"https:\/\/www.avenida12.com\/privacy-policy\/\">informativa<\/a> ed acconsento al trattamento dei dati personali.\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send message\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1126b8d9 elementor-widget elementor-widget-spacer\" data-id=\"1126b8d9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact us to book your rented room. And if you wish, request your self check-in. For a relaxing, easy-going and unforgettable stay in Alghero, choose Avenida12! Your Name Your email Your message Ai sensi e per gli effetti degli articoli artt. 7,13 e 15 del Regolamento UE 2016\/679 dichiaro di aver preso visione dell\u2019 informativa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-843","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact us - Avenida 12<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.avenida12.com\/en\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact us - Avenida 12\" \/>\n<meta property=\"og:description\" content=\"Contact us to book your rented room. And if you wish, request your self check-in. For a relaxing, easy-going and unforgettable stay in Alghero, choose Avenida12! Your Name Your email Your message Ai sensi e per gli effetti degli articoli artt. 7,13 e 15 del Regolamento UE 2016\/679 dichiaro di aver preso visione dell\u2019 informativa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.avenida12.com\/en\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Avenida 12\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-15T10:22:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.avenida12.com\/en\/contact-us\/\",\"url\":\"https:\/\/www.avenida12.com\/en\/contact-us\/\",\"name\":\"Contact us - Avenida 12\",\"isPartOf\":{\"@id\":\"https:\/\/www.avenida12.com\/#website\"},\"datePublished\":\"2023-04-13T10:41:44+00:00\",\"dateModified\":\"2023-05-15T10:22:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.avenida12.com\/en\/contact-us\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.avenida12.com\/en\/contact-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.avenida12.com\/en\/contact-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.avenida12.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.avenida12.com\/#website\",\"url\":\"https:\/\/www.avenida12.com\/\",\"name\":\"Avenida 12\",\"description\":\"Alghero Rooms\",\"publisher\":{\"@id\":\"https:\/\/www.avenida12.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.avenida12.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.avenida12.com\/#organization\",\"name\":\"Avenida 12\",\"url\":\"https:\/\/www.avenida12.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.avenida12.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.avenida12.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/www.avenida12.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":232,\"height\":128,\"caption\":\"Avenida 12\"},\"image\":{\"@id\":\"https:\/\/www.avenida12.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact us - Avenida 12","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.avenida12.com\/en\/contact-us\/","og_locale":"en_US","og_type":"article","og_title":"Contact us - Avenida 12","og_description":"Contact us to book your rented room. And if you wish, request your self check-in. For a relaxing, easy-going and unforgettable stay in Alghero, choose Avenida12! Your Name Your email Your message Ai sensi e per gli effetti degli articoli artt. 7,13 e 15 del Regolamento UE 2016\/679 dichiaro di aver preso visione dell\u2019 informativa [&hellip;]","og_url":"https:\/\/www.avenida12.com\/en\/contact-us\/","og_site_name":"Avenida 12","article_modified_time":"2023-05-15T10:22:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.avenida12.com\/en\/contact-us\/","url":"https:\/\/www.avenida12.com\/en\/contact-us\/","name":"Contact us - Avenida 12","isPartOf":{"@id":"https:\/\/www.avenida12.com\/#website"},"datePublished":"2023-04-13T10:41:44+00:00","dateModified":"2023-05-15T10:22:53+00:00","breadcrumb":{"@id":"https:\/\/www.avenida12.com\/en\/contact-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.avenida12.com\/en\/contact-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.avenida12.com\/en\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.avenida12.com\/en\/"},{"@type":"ListItem","position":2,"name":"Contact us"}]},{"@type":"WebSite","@id":"https:\/\/www.avenida12.com\/#website","url":"https:\/\/www.avenida12.com\/","name":"Avenida 12","description":"Alghero Rooms","publisher":{"@id":"https:\/\/www.avenida12.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.avenida12.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.avenida12.com\/#organization","name":"Avenida 12","url":"https:\/\/www.avenida12.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.avenida12.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.avenida12.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/www.avenida12.com\/wp-content\/uploads\/2023\/04\/logo.png","width":232,"height":128,"caption":"Avenida 12"},"image":{"@id":"https:\/\/www.avenida12.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/pages\/843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/comments?post=843"}],"version-history":[{"count":10,"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/pages\/843\/revisions"}],"predecessor-version":[{"id":1015,"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/pages\/843\/revisions\/1015"}],"wp:attachment":[{"href":"https:\/\/www.avenida12.com\/en\/wp-json\/wp\/v2\/media?parent=843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}